{"id":8365,"date":"2013-08-27T01:44:19","date_gmt":"2013-08-26T23:44:19","guid":{"rendered":"http:\/\/tuxproject.de\/blog\/?p=8365"},"modified":"2013-08-27T04:46:56","modified_gmt":"2013-08-27T02:46:56","slug":"piratenleaks-27-august-2013","status":"publish","type":"post","link":"https:\/\/tuxproject.de\/blog\/2013\/08\/piratenleaks-27-august-2013\/","title":{"rendered":"Pira\u00adten\u00adleaks, 27. August 2013"},"content":{"rendered":"<p>Nach\u00addem im Wahl\u00adjahr 2013 von eini\u00adgen Par\u00adtei\u00aden schon unsch\u00f6\u00adne Details aus der Ver\u00adgan\u00adgen\u00adheit (bei der F.D.P. das mit der Abstim\u00admung gegen <a href=\"http:\/\/www.fakeblog.de\/2013\/08\/23\/fdp-wird-neuland-opfer-2\/\">dop\u00adpel\u00adte Staats\u00adb\u00fcr\u00adger\u00adschaft<\/a> und <a href=\"http:\/\/www.fakeblog.de\/2013\/08\/23\/fdp-wird-neuland-opfer\/\">Gleich\u00adbe\u00adrech\u00adti\u00adgung bei Ehe\u00adschlie\u00ad\u00dfun\u00adgen<\/a>, bei den Gr\u00fc\u00adnen das mit dem Kin\u00adder\u00adficken) an die Ober\u00adfl\u00e4\u00adche gesp\u00fclt wur\u00adden, k\u00f6n\u00adnen nat\u00fcr\u00adlich auch die Pira\u00adten nicht hin\u00adten anste\u00adhen.<\/p>\n<p>Klar ist gera\u00adde in einer digi\u00adtal ver\u00adnetz\u00adten Par\u00adtei die Gefahr gro\u00df, dass sich Kl\u00fcn\u00adgel bil\u00addet. Nur sel\u00adten wird das \u00f6ffent\u00adlich gemacht. <\/p>\n<p>Aktu\u00adell wird auf der inter\u00adnen Mai\u00adling\u00adli\u00adste des nie\u00adder\u00ads\u00e4ch\u00adsi\u00adschen Lan\u00addes\u00advor\u00adstands ein pikan\u00adter Sach\u00adver\u00adhalt dis\u00adku\u00adtiert: Offen\u00adbar <a href=\"http:\/\/webcache.googleusercontent.com\/search?q=cache:tgozp88mzDoJ:https:\/\/lists.piraten-nds.de\/mailman\/listinfo\/lv-p-k%20&amp;cd=4&amp;hl=de&amp;ct=clnk&amp;gl=de\">exi\u00adstier\u00adte<\/a> <em>(Vor\u00adsicht: Ver\u00adweis auf NSA-Goog\u00adle!)<\/em> bis vor kur\u00adzem eine Mai\u00adling\u00adli\u00adste namens \u201ePres\u00adse\u00adko\u00ador\u00addi\u00adna\u00adti\u00adon der Lan\u00addes\u00adver\u00adb\u00e4n\u00adde\u201c, in die nicht alle Pres\u00adse\u00adspre\u00adcher und nicht alle Lan\u00addes\u00advor\u00adst\u00e4n\u00adde, wohl aber aller\u00adlei ehe\u00adma\u00adli\u00adge Vor\u00adst\u00e4n\u00adde Ein\u00adsicht erhal\u00adten. Die Dis\u00adkus\u00adsi\u00adon auf der Mai\u00adling\u00adli\u00adste ist recht erhel\u00adlend:<\/p>\n<p><a href=\"https:\/\/tuxproject.de\/blog\/wp-content\/uploads\/2013\/08\/Kl\u00fcngel.txt\">Spie\u00adge\u00adlung in Text\u00adform<\/a> (<a href=\"http:\/\/pastebin.com\/giMxz7xR\">Quel\u00adle<\/a>)<\/p>\n<p>Nun wur\u00adden, wohl um Spu\u00adren zu ver\u00adwi\u00adschen, fol\u00adgen\u00adde drei \u201eTickets\u201c, also Antr\u00e4\u00adge, gestellt, die wahl\u00adwei\u00adse die Ver\u00ad\u00f6f\u00adfent\u00adli\u00adchung oder die L\u00f6schung des vor\u00adhan\u00adde\u00adnen Archivs besag\u00adter Mai\u00adling\u00adli\u00adste zum Inhalt haben. (Lei\u00adder ist mir das Archiv selbst nicht zug\u00e4ng\u00adlich.)<\/p>\n<ul>\n<li><a href=\"https:\/\/ticket.piraten-nds.de\/issues\/14552\">https:\/\/ticket.piraten-nds.de\/issues\/14552<\/a><\/li>\n<li><a href=\"https:\/\/ticket.piraten-nds.de\/issues\/13927\">https:\/\/ticket.piraten-nds.de\/issues\/13927<\/a><\/li>\n<li><a href=\"https:\/\/ticket.piraten-nds.de\/issues\/14536\">https:\/\/ticket.piraten-nds.de\/issues\/14536<\/a> (momen\u00adtan nicht \u00f6ffent\u00adlich, Spie\u00adgel <a href=\"https:\/\/tuxproject.de\/blog\/wp-content\/uploads\/2013\/08\/Ticket-von-Mario-G\u00e4rtner-Espenschied.txt\">hier<\/a>, <a href=\"http:\/\/pastebin.com\/yUARXgNn\">Quel\u00adle<\/a>)<\/li>\n<\/ul>\n<p>Lesens\u00adwert ist hier\u00adbei vor allem der Kon\u00adtrast zwi\u00adschen Bef\u00fcr\u00adwor\u00adtern und Geg\u00adnern der Frei\u00adga\u00adbe. F\u00fcr Rechen\u00adk\u00fcnst\u00adler \u00fcbri\u00adgens noch fol\u00adgen\u00addes Gedan\u00adken\u00adspiel: Der nie\u00adder\u00ads\u00e4ch\u00adsi\u00adsche Lan\u00addes\u00advor\u00adstand hat zur\u00adzeit 11 Mit\u00adglie\u00adder, um eine Frei\u00adga\u00adbe des Archivs zu errei\u00adchen, m\u00fcss\u00adte es also min\u00adde\u00adstens 6 Daf\u00fcr-Stim\u00admen geben. Dass es kei\u00adne sech\u00adste gibt <del>(und nicht ein\u00admal der erste Vor\u00adsit\u00adzen\u00adde bis\u00adlang abge\u00adstimmt hat)<\/del>, ist ver\u00admut\u00adlich kein Zufall, wenn man den Chat\u00adaus\u00adschnitt von der Mai\u00adling\u00adli\u00adste ber\u00fcck\u00adsich\u00adtigt.<\/p>\n<p>Ich fas\u00adse zusam\u00admen: Ein ehe\u00adma\u00adli\u00adges Mit\u00adglied des Lan\u00addes\u00advor\u00adstands (Tho\u00admas Gaul), der momen\u00adtan als Koor\u00addi\u00adna\u00adtor f\u00fcr die <em>Pira\u00adte Par\u00adty Inter\u00adna\u00adtio\u00adnal<\/em> t\u00e4tig ist, hat also mit\u00adhil\u00adfe einer <em>gehei\u00admen<\/em> Mai\u00adling\u00adli\u00adste, in die nicht jeder rein\u00adkommt (<a href=\"https:\/\/tuxproject.de\/blog\/2010\/02\/piratinnen-klarmachen-zum-was\/\">wir erin\u00adnern uns<\/a>), und eines als Bei\u00adsit\u00adzer erneut gew\u00e4hl\u00adten Mit\u00adglieds des Lan\u00addes\u00advor\u00adstands (Mario Espen\u00adschied) sel\u00adbi\u00adgen Vor\u00adstand offen\u00adbar voll im Griff und schreckt beim Ver\u00adsuch, die\u00adsen Griff hal\u00adten zu k\u00f6n\u00adnen, auch vor Erpres\u00adsungs\u00adver\u00adsu\u00adchen nicht zur\u00fcck. <a href=\"http:\/\/twitter.com\/Thomas1G\/status\/372135124382392321\">Und wie er sich dar\u00ad\u00fcber freut!<\/a> Nat\u00fcr\u00adlich <em>k\u00f6nn\u00adte<\/em> man die\u00adsen Herrn ein\u00adfach unsanft vor die T\u00fcr set\u00adzen, aber so kurz vor der Wahl ist schlech\u00adte <em>publi\u00adci\u00adty<\/em> wom\u00f6g\u00adlich nicht erstre\u00adbens\u00adwert. Die <em>basis\u00adde\u00admo\u00adkra\u00adti\u00adsche Mit\u00adbe\u00adstim\u00admung<\/em> (Open\u00adAn\u00adtrag hat\u00adte ich ja bereits <a href=\"https:\/\/tuxproject.de\/blog\/2013\/08\/hannes-wader-und-toten-hosen-heute-hier-morgen-dort\/\">als posi\u00adti\u00adve Neue\u00adrung her\u00adaus\u00adge\u00adstellt<\/a>) nimmt gele\u00adgent\u00adlich impo\u00adsan\u00adte Aus\u00adma\u00ad\u00dfe an.<\/p>\n<p>Der nie\u00adder\u00ads\u00e4ch\u00adsi\u00adsche Lan\u00addes\u00advor\u00adstand wird zur\u00adzeit von Kevin Pri\u00adce gelei\u00adtet, der in sei\u00adnen E\u2011Mails an den Lan\u00addes\u00adver\u00adband Nie\u00adder\u00adsach\u00adsen nicht sel\u00adten das Trans\u00adpa\u00adrenz\u00adge\u00adbot erw\u00e4hnt, dem er sich selbst unter\u00adwor\u00adfen sieht. Ich \u00fcber\u00adneh\u00adme das jetzt mal f\u00fcr ihn.<\/p>\n<p>(Quel\u00adle: Inter\u00adnet.)<\/p>\n<hr>\n<p>Nach\u00adtrag 1: Soeben wur\u00adden zwei der drei Tickets ge\u00f6ff\u00adnet, Kevin hat jetzt auch abge\u00adstimmt.<\/p>\n<p>Nach\u00adtrag 2: Um 3:56 Uhr hat Kevin Pri\u00adce sich \u2013 laut eige\u00adner Aus\u00adsa\u00adge zwei Wochen nach erst\u00adma\u00adli\u00adger Kennt\u00adnis\u00adnah\u00adme vom Sach\u00adver\u00adhalt \u2013 <a href=\"https:\/\/news.piratenpartei.de\/showthread.php?tid=369837\">\u00f6ffent\u00adlich<\/a> zu dem Vor\u00adfall ge\u00e4u\u00ad\u00dfert (<a href=\"https:\/\/tuxproject.de\/blog\/wp-content\/uploads\/2013\/08\/Kevin.txt\">Spie\u00adgel hier<\/a>).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nach\u00addem im Wahl\u00adjahr 2013 von eini\u00adgen Par\u00adtei\u00aden schon unsch\u00f6\u00adne Details aus der Ver\u00adgan\u00adgen\u00adheit (bei der F.D.P. das mit der Abstim\u00admung gegen dop\u00adpel\u00adte Staats\u00adb\u00fcr\u00adger\u00adschaft und Gleich\u00adbe\u00adrech\u00adti\u00adgung bei Ehe\u00adschlie\u00ad\u00dfun\u00adgen, bei den Gr\u00fc\u00adnen das mit dem Kin\u00adder\u00adficken) an die Ober\u00adfl\u00e4\u00adche gesp\u00fclt wur\u00adden, k\u00f6n\u00adnen nat\u00fcr\u00adlich auch die Pira\u00adten nicht hin\u00adten anste\u00adhen. Klar ist gera\u00adde in einer digi\u00adtal ver\u00adnetz\u00adten Par\u00adtei \u2026<\/p>\n<p><a href=\"https:\/\/tuxproject.de\/blog\/2013\/08\/piratenleaks-27-august-2013\/\" class=\"more-link\">\u2018Pira\u00adten\u00adleaks, 27. August 2013\u2019 wei\u00adter\u00adle\u00adsen \u00bb<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"wp_typography_post_enhancements_disabled":false,"activitypub_content_warning":"","activitypub_content_visibility":"","activitypub_max_image_attachments":3,"activitypub_interaction_policy_quote":"anyone","activitypub_status":"","footnotes":""},"categories":[20],"tags":[],"series":[],"class_list":["post-8365","post","type-post","status-publish","format-standard","hentry","category-piratenpartei"],"share_on_mastodon":{"url":"","error":""},"wp-worthy-pixel":{"ignored":false,"public":null,"server":null,"url":null},"wp-worthy-type":"normal","_links":{"self":[{"href":"https:\/\/tuxproject.de\/blog\/wp-json\/wp\/v2\/posts\/8365","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tuxproject.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tuxproject.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tuxproject.de\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tuxproject.de\/blog\/wp-json\/wp\/v2\/comments?post=8365"}],"version-history":[{"count":0,"href":"https:\/\/tuxproject.de\/blog\/wp-json\/wp\/v2\/posts\/8365\/revisions"}],"wp:attachment":[{"href":"https:\/\/tuxproject.de\/blog\/wp-json\/wp\/v2\/media?parent=8365"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tuxproject.de\/blog\/wp-json\/wp\/v2\/categories?post=8365"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tuxproject.de\/blog\/wp-json\/wp\/v2\/tags?post=8365"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/tuxproject.de\/blog\/wp-json\/wp\/v2\/series?post=8365"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}