{"id":6570,"date":"2012-06-19T22:09:59","date_gmt":"2012-06-19T20:09:59","guid":{"rendered":"http:\/\/tuxproject.de\/blog\/?p=6570"},"modified":"2012-06-19T22:12:24","modified_gmt":"2012-06-19T20:12:24","slug":"na-endlich-der-sozialismus-rettet-den-euro","status":"publish","type":"post","link":"https:\/\/tuxproject.de\/blog\/2012\/06\/na-endlich-der-sozialismus-rettet-den-euro\/","title":{"rendered":"Na end\u00adlich: Der Sozia\u00adlis\u00admus ret\u00adtet den Euro"},"content":{"rendered":"<p>F\u00fcr das Han\u00addels\u00adblatt schw\u00e4tzt <del>Franz<\/del> Max Josef Strau\u00df heu\u00adte zum The\u00adma Koali\u00adti\u00adons\u00adbil\u00addung in Grie\u00adchen\u00adland <a href=\"http:\/\/www.handelsblatt.com\/meinung\/gastbeitraege\/max-josef-strauss-griechen-haetten-die-radikale-linke-waehlen-sollen\/6765896.html\">dies ins Inter\u00adnet hin\u00adein:<\/a><\/p>\n<blockquote><p>Schei\u00adtert der Auf\u00adbau einer moder\u00adnen Ver\u00adwal\u00adtung in Athen, ist ein wirt\u00adschaft\u00adli\u00adcher Auf\u00adschwung nahe\u00adzu aus\u00adge\u00adschlos\u00adsen, was zu mas\u00adsi\u00adven sozia\u00adlen Pro\u00adble\u00admen f\u00fch\u00adren w\u00fcr\u00adde.<\/p>\n<p>Dann droht das Land dau\u00ader\u00adhaft zum teu\u00adren Kost\u00adg\u00e4n\u00adger Euro\u00adpas zu wer\u00adden, und nie\u00admand braucht davon zu tr\u00e4u\u00admen, dass dann die grie\u00adchi\u00adschen Staats\u00adan\u00adlei\u00adhen jemals zur\u00fcck\u00adbe\u00adzahlt wer\u00adden. Der euro\u00adp\u00e4i\u00adsche Steu\u00ader\u00adzah\u00adler m\u00fcss\u00adte dann im Namen der Euro-Ret\u00adtung die\u00adse Last schul\u00adtern, was ein schlim\u00admes Signal an ande\u00adre s\u00fcd- oder ost\u00adeu\u00adro\u00adp\u00e4i\u00adsche Ver\u00adwal\u00adtun\u00adgen und eine schwe\u00adre Hypo\u00adthek f\u00fcr den euro\u00adp\u00e4i\u00adschen Eini\u00adgungs\u00adpro\u00adzess w\u00e4re.<\/p><\/blockquote>\n<p>Grie\u00adchen\u00adland, der teu\u00adre Kost\u00adg\u00e4n\u00adger Euro\u00adpas mit mas\u00adsi\u00adven sozia\u00adlen Pro\u00adble\u00admen (der Spar\u00adkurs treibt zum Bei\u00adspiel <a href=\"http:\/\/library.fes.de\/pdf-files\/id\/ipa\/08226.pdf\">die dor\u00adti\u00adgen Arbeits\u00adlo\u00adsen\u00adzah\u00adlen in die H\u00f6he<\/a>), des\u00adsen Staats\u00adan\u00adlei\u00adhen wohl nie\u00admand je wie\u00adder\u00adse\u00adhen wird und des\u00adsen Miss\u00adwirt\u00adschaft von <em>uns<\/em>, den <em>rei\u00adchen<\/em> Euro\u00adl\u00e4n\u00addern, im Namen der \u201eEuro-Ret\u00adtung\u201c (Strau\u00df) aus\u00adge\u00adgli\u00adchen wer\u00adden muss, w\u00fcr\u00adde ohne eine moder\u00adne Ver\u00adwal\u00adtung also blei\u00adben, was es jetzt ist.<\/p>\n<p>Aber wie sieht eine \u201emoder\u00adne Ver\u00adwal\u00adtung\u201c aus? Tja, das fin\u00addet man ganz ein\u00adfach her\u00adaus, indem man die radi\u00adkal\u00adso\u00adzia\u00adli\u00adsti\u00adsche Par\u00adtei SYRIZA w\u00e4hlt:<\/p>\n<blockquote><p>Syri\u00adza ist wohl die ein\u00adzi\u00adge M\u00f6g\u00adlich\u00adkeit, dass die Grie\u00adchen aus eige\u00adner Kraft die bis\u00adhe\u00adri\u00adgen kor\u00adrup\u00adten \u201eEli\u00adten\u201c abl\u00f6\u00adsen k\u00f6nn\u00adten, weil es den R\u00fccken frei hat und nicht auf ver\u00adgan\u00adge\u00adne Ver\u00adstrickun\u00adgen R\u00fcck\u00adsicht neh\u00admen muss. Dass Tsi\u00adpras mit dem Aus\u00adstieg aus dem Euro \u2013 und den damit ver\u00adbun\u00adde\u00adnen Ver\u00adlu\u00adsten der Gl\u00e4u\u00adbi\u00adger Grie\u00adchen\u00adlands \u2013 droh\u00adte, soll\u00adten wir ihm als not\u00adwen\u00addi\u00adgen Thea\u00adter\u00addon\u00adner und Wahl\u00adkampf\u00adrhe\u00adto\u00adrik zubil\u00adli\u00adgen.<\/p><\/blockquote>\n<p>Kor\u00adrup\u00adte Eli\u00adten wird man am ein\u00adfach\u00adsten los, indem man eine links\u00adra\u00addi\u00adka\u00adle Regie\u00adrung w\u00e4hlt, das hat ja auch in Deutsch\u00adland \u2013 dr\u00fc\u00adben <em>in der Zone<\/em> \u2013 schon mal so gut funk\u00adtio\u00adniert, dass eini\u00adge von ihnen immer noch eini\u00adger\u00adma\u00ad\u00dfen hohe poli\u00adti\u00adsche \u00c4mter in die\u00adsem Land beklei\u00adden. Dass der Vor\u00adsit\u00adzen\u00adde der SYRIZA den Euro abzu\u00adschaf\u00adfen for\u00addert, ist sicher nur ein Witz von ihm und gar nicht so gemeint, denn dann s\u00e4he es mit der R\u00fcck\u00adzah\u00adlung der <em>gelie\u00adhe\u00adnen<\/em> Euro auch eher d\u00fcster aus, und war\u00adum soll\u00adte Grie\u00adchen\u00adland sei\u00adne Schul\u00adden nicht zur\u00fcck\u00adzah\u00adlen wol\u00adlen? Das w\u00e4re doch nicht nett.<\/p>\n<p>Und so schlimm ist das ja auch gar nicht mit den Alb\u00adtr\u00e4u\u00admen von der lin\u00adken Ter\u00adror\u00adherr\u00adschaft, sagt der Strau\u00df, weil Deutsch\u00adland mit Links\u00adra\u00addi\u00adka\u00adlen bis\u00adher erstaun\u00adlich gut zurecht\u00adge\u00adkom\u00admen sei:<\/p>\n<blockquote><p>Wir soll\u00adten uns viel\u00adleicht an unse\u00adre eige\u00adne Geschich\u00adte erin\u00adnern, n\u00e4m\u00adlich dar\u00adan, dass 1968 auch bei uns Pro\u00adte\u00adstie\u00adrer in Mas\u00adsen hin\u00adter den Bil\u00addern kom\u00admu\u00adni\u00adsti\u00adscher Unter\u00addr\u00fccker und Dik\u00adta\u00adto\u00adren her\u00adlie\u00adfen, um das b\u00fcr\u00adger\u00adli\u00adche Estab\u00adlish\u00adment zu erschrecken. Aus ihnen gin\u00adgen im Lau\u00adfe der Jah\u00adre vie\u00adle demo\u00adkra\u00adti\u00adsche Par\u00adla\u00admen\u00adta\u00adri\u00ader und Bun\u00addes\u00admi\u00adni\u00adster her\u00advor, die so gar nichts mit den Bil\u00addern gemein haben, hin\u00adter denen sie mal her\u00adge\u00adlau\u00adfen sind.<\/p><\/blockquote>\n<p>Der Bekann\u00adte\u00adste die\u00adser Par\u00adla\u00admen\u00adta\u00adri\u00ader und Bun\u00addes\u00admi\u00adni\u00adster ist wahr\u00adschein\u00adlich \u201eJosch\u00adka\u201c Fischer, der als fr\u00fc\u00adhe\u00adrer Bun\u00addes\u00adau\u00ad\u00dfen\u00admi\u00adni\u00adster nicht nur den ersten deut\u00adschen Angriffs\u00adkrieg seit 1945 zu ver\u00adant\u00adwor\u00adten hat, zu ihnen geh\u00f6rt des Wei\u00adte\u00adren Otto Schi\u00adly, Tr\u00e4\u00adger des Big Brot\u00adher Life\u00adtime Awards 2005 \u201ef\u00fcr den Aus\u00adbau des deut\u00adschen und euro\u00adp\u00e4i\u00adschen \u00dcber\u00adwa\u00adchungs\u00adsy\u00adstems auf Kosten der B\u00fcr\u00adger- und Frei\u00adheits\u00adrech\u00adte und f\u00fcr sei\u00adne hart\u00adn\u00e4cki\u00adgen Bem\u00fc\u00adhun\u00adgen um die Aus\u00adh\u00f6h\u00adlung des Daten\u00adschut\u00adzes unter dem Deck\u00adman\u00adtel von Sicher\u00adheit und Ter\u00adror\u00adbe\u00adk\u00e4mp\u00adfung\u201c.<\/p>\n<p>Genau sol\u00adche Leu\u00adte braucht Grie\u00adchen\u00adland. Die wis\u00adsen noch, wor\u00adauf es ankommt.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>F\u00fcr das Han\u00addels\u00adblatt schw\u00e4tzt Franz Max Josef Strau\u00df heu\u00adte zum The\u00adma Koali\u00adti\u00adons\u00adbil\u00addung in Grie\u00adchen\u00adland dies ins Inter\u00adnet hin\u00adein: Schei\u00adtert der Auf\u00adbau einer moder\u00adnen Ver\u00adwal\u00adtung in Athen, ist ein wirt\u00adschaft\u00adli\u00adcher Auf\u00adschwung nahe\u00adzu aus\u00adge\u00adschlos\u00adsen, was zu mas\u00adsi\u00adven sozia\u00adlen Pro\u00adble\u00admen f\u00fch\u00adren w\u00fcr\u00adde. Dann droht das Land dau\u00ader\u00adhaft zum teu\u00adren Kost\u00adg\u00e4n\u00adger Euro\u00adpas zu wer\u00adden, und nie\u00admand braucht davon zu \u2026<\/p>\n<p><a href=\"https:\/\/tuxproject.de\/blog\/2012\/06\/na-endlich-der-sozialismus-rettet-den-euro\/\" class=\"more-link\">\u2018Na end\u00adlich: Der Sozia\u00adlis\u00admus ret\u00adtet den Euro\u2019 wei\u00adter\u00adle\u00adsen \u00bb<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"wp_typography_post_enhancements_disabled":false,"activitypub_content_warning":"","activitypub_content_visibility":"","activitypub_max_image_attachments":3,"activitypub_interaction_policy_quote":"anyone","activitypub_status":"","footnotes":""},"categories":[13,29],"tags":[],"series":[],"class_list":["post-6570","post","type-post","status-publish","format-standard","hentry","category-in-den-nachrichten","category-wirtschaft"],"share_on_mastodon":{"url":"","error":""},"wp-worthy-pixel":{"ignored":false,"public":null,"server":null,"url":null},"wp-worthy-type":"normal","_links":{"self":[{"href":"https:\/\/tuxproject.de\/blog\/wp-json\/wp\/v2\/posts\/6570","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tuxproject.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tuxproject.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tuxproject.de\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tuxproject.de\/blog\/wp-json\/wp\/v2\/comments?post=6570"}],"version-history":[{"count":0,"href":"https:\/\/tuxproject.de\/blog\/wp-json\/wp\/v2\/posts\/6570\/revisions"}],"wp:attachment":[{"href":"https:\/\/tuxproject.de\/blog\/wp-json\/wp\/v2\/media?parent=6570"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tuxproject.de\/blog\/wp-json\/wp\/v2\/categories?post=6570"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tuxproject.de\/blog\/wp-json\/wp\/v2\/tags?post=6570"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/tuxproject.de\/blog\/wp-json\/wp\/v2\/series?post=6570"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}