{"id":21322,"date":"2023-10-03T20:28:11","date_gmt":"2023-10-03T18:28:11","guid":{"rendered":"https:\/\/tuxproject.de\/blog\/?p=21322"},"modified":"2023-10-03T20:28:11","modified_gmt":"2023-10-03T18:28:11","slug":"die-grenze-durch-europa","status":"publish","type":"post","link":"https:\/\/tuxproject.de\/blog\/2023\/10\/die-grenze-durch-europa\/","title":{"rendered":"Die Gren\u00adze durch Euro\u00adpa"},"content":{"rendered":"<p>1990 hat die Treu\u00adhand\u00adge\u00adsell\u00adschaft ein Land pri\u00adva\u00adti\u00adsiert und die CDU eine Gesell\u00adschaft ihrer Grund\u00adla\u00adge beraubt. Fr\u00f6h\u00adli\u00adcher Fei\u00ader\u00adtag und sal\u00adbungs\u00advol\u00adle Wor\u00adte des Wahl\u00admon\u00adar\u00adchen sind gesetzt. Nur kei\u00adne Fra\u00adgen stel\u00adlen. Das spielt <em>denen<\/em> in die H\u00e4n\u00adde.<\/p>\n<p>Rote oder blaue Pil\u00adle?<\/p>\n<p>In Tei\u00adlen Finn\u00adlands wird G\u00e4sten <a href=\"https:\/\/www.thecut.com\/2018\/11\/what-is-coffee-cheese-kaffeost.html\">Kaf\u00adfee mit K\u00e4se<\/a> gereicht. Wo ist Gen\u00adscher, wenn man ihn mal braucht?<\/p>\n","protected":false},"excerpt":{"rendered":"<p>1990 hat die Treu\u00adhand\u00adge\u00adsell\u00adschaft ein Land pri\u00adva\u00adti\u00adsiert und die CDU eine Gesell\u00adschaft ihrer Grund\u00adla\u00adge beraubt. Fr\u00f6h\u00adli\u00adcher Fei\u00ader\u00adtag und sal\u00adbungs\u00advol\u00adle Wor\u00adte des Wahl\u00admon\u00adar\u00adchen sind gesetzt. Nur kei\u00adne Fra\u00adgen stel\u00adlen. Das spielt denen in die H\u00e4n\u00adde. Rote oder blaue Pil\u00adle? In Tei\u00adlen Finn\u00adlands wird G\u00e4sten Kaf\u00adfee mit K\u00e4se gereicht. Wo ist Gen\u00adscher, wenn man ihn mal braucht?<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"wp_typography_post_enhancements_disabled":false,"activitypub_content_warning":"","activitypub_content_visibility":"","activitypub_max_image_attachments":3,"activitypub_interaction_policy_quote":"anyone","activitypub_status":"","footnotes":""},"categories":[4],"tags":[],"series":[],"class_list":["post-21322","post","type-post","status-publish","format-standard","hentry","category-politik"],"share_on_mastodon":{"url":"https:\/\/social.tchncs.de\/@hirnfick_20\/111172497727965363","error":""},"wp-worthy-pixel":{"ignored":false,"public":null,"server":null,"url":null},"wp-worthy-type":"normal","_links":{"self":[{"href":"https:\/\/tuxproject.de\/blog\/wp-json\/wp\/v2\/posts\/21322","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tuxproject.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tuxproject.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tuxproject.de\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tuxproject.de\/blog\/wp-json\/wp\/v2\/comments?post=21322"}],"version-history":[{"count":0,"href":"https:\/\/tuxproject.de\/blog\/wp-json\/wp\/v2\/posts\/21322\/revisions"}],"wp:attachment":[{"href":"https:\/\/tuxproject.de\/blog\/wp-json\/wp\/v2\/media?parent=21322"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tuxproject.de\/blog\/wp-json\/wp\/v2\/categories?post=21322"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tuxproject.de\/blog\/wp-json\/wp\/v2\/tags?post=21322"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/tuxproject.de\/blog\/wp-json\/wp\/v2\/series?post=21322"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}