{"id":20771,"date":"2023-04-10T08:30:16","date_gmt":"2023-04-10T06:30:16","guid":{"rendered":"https:\/\/tuxproject.de\/blog\/?p=20771"},"modified":"2023-04-10T05:29:45","modified_gmt":"2023-04-10T03:29:45","slug":"when-plagues-collide-tears-of-a-king-heuschrecken-und-ihre-fuehrer","status":"publish","type":"post","link":"https:\/\/tuxproject.de\/blog\/2023\/04\/when-plagues-collide-tears-of-a-king-heuschrecken-und-ihre-fuehrer\/","title":{"rendered":"When Pla\u00adgues Col\u00adl\u00adi\u00adde \u2013 Tears of a King \/\/ Heu\u00adschrecken und ihre F\u00fch\u00adrer"},"content":{"rendered":"<p><a href=\"https:\/\/tuxproject.de\/blog\/wp-content\/uploads\/2023\/04\/Lebensgefuehl-ca.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/tuxproject.de\/blog\/wp-content\/uploads\/2023\/04\/Lebensgefuehl-ca-120x110.jpg\" alt=\"Lebensgef\u00fchl (ca.)\" width=\"120\" height=\"110\" class=\"alignright size-thumbnail wp-image-20772\" srcset=\"https:\/\/tuxproject.de\/blog\/wp-content\/uploads\/2023\/04\/Lebensgefuehl-ca-120x110.jpg 120w, https:\/\/tuxproject.de\/blog\/wp-content\/uploads\/2023\/04\/Lebensgefuehl-ca-300x276.jpg 300w, https:\/\/tuxproject.de\/blog\/wp-content\/uploads\/2023\/04\/Lebensgefuehl-ca.jpg 500w\" sizes=\"auto, (max-width: 120px) 100vw, 120px\"><\/a>Es ist Mon\u00adtag. RAAAAAAAH! So, geht wie\u00adder.<\/p>\n<p>Die Gali\u00adons\u00adfi\u00adgur der th\u00fc\u00adrin\u00adgi\u00adschen Lin\u00adken tei\u00adle mit, ent\u00adneh\u00adme ich <a href=\"https:\/\/feynsinn.org\/?p=9546\">einer ande\u00adren Publi\u00adka\u00adti\u00adon<\/a>, dass Putin schlim\u00admer, weil form\u00advoll\u00adende\u00adter sei als Hit\u00adler. Da kann ja nichts mehr schief\u00adge\u00adhen bei der n\u00e4ch\u00adsten Wahl. Ein furcht\u00adba\u00adrer F\u00fch\u00adrer scheint auch bei MariaDB.com, dem Heu\u00adschrecken\u00adkon\u00adzern hin\u00adter der MariaDB-Daten\u00adbank, <a href=\"https:\/\/medium.com\/@imashadowphantom\/mariadb-com-is-dead-long-live-mariadb-org-b8a0ca50a637\">am Werk zu sein<\/a>, was lustig ist, weil MariaDB selbst ja als Ersatz f\u00fcr MySQL ent\u00adwickelt wur\u00adde, weil die\u00adses von einem Heu\u00adschrecken\u00adkon\u00adzern (n\u00e4m\u00adlich Ora\u00adcle) gekauft wor\u00adden war und die Ent\u00adwick\u00adler das nicht woll\u00adten. Fast scheint es mir, als mache Geld alles Gute zunich\u00adte. Um Qua\u00adli\u00adt\u00e4t geht es jeden\u00adfalls <a href=\"https:\/\/blog.fefe.de\/?ts=9ad1e11a\">l\u00e4ngst nicht mehr<\/a>, sonst w\u00e4re Com\u00adpu\u00adter\u00adsi\u00adcher\u00adheit qua\u00adsi selbst\u00adver\u00adst\u00e4nd\u00adlich.<\/p>\n<p>Apro\u00adpos Heu\u00adschrecken\u00adkon\u00adzer\u00adne: Die Musik\u00adin\u00addu\u00adstrie, die irgend\u00adein Ham\u00admel immer noch frei im Inter\u00adnet her\u00adum\u00adma\u00adro\u00addie\u00adren l\u00e4sst, ver\u00adsucht <a href=\"https:\/\/freiheitsrechte.org\/themen\/demokratie\/uberspace-youtube-dl\">immer noch<\/a> den frei\u00aden Kul\u00adtur- und Wis\u00adsens\u00adaus\u00adtausch zu einem teu\u00adren Luxus zu per\u00adver\u00adtie\u00adren. So lan\u00adge man ihre Ver\u00adtre\u00adter nicht geteert, gefe\u00addert und ins n\u00e4ch\u00adste Abschie\u00adbe\u00adflug\u00adzeug gesetzt hat, scheint es mir gebo\u00adten zu sein, sich beim Musik\u00adge\u00adnuss ein wenig zu beei\u00adlen. Ich lege mal vor.<\/p>\n<div class=\"lyte-wrapper\" title=\"WHEN PLAGUES COLLIDE - TEARS OF A KING [OFFICIAL MUSIC VIDEO] (2020) SW EXCLUSIVE\" style=\"width:1280px;max-width:100%;margin:5px;\"><div class=\"lyMe\" id=\"WYL_dEUJwSJbKUc\"><div id=\"lyte_dEUJwSJbKUc\" data-src=\"https:\/\/tuxproject.de\/blog\/wp-content\/plugins\/wp-youtube-lyte\/lyteCache.php?origThumbUrl=https%3A%2F%2Fi.ytimg.com%2Fvi%2FdEUJwSJbKUc%2Fhqdefault.jpg\" class=\"pL\"><div class=\"tC\"><div class=\"tT\">WHEN PLAGUES COLLIDE \u2013 TEARS OF A KING [OFFICIAL MUSIC VIDEO] (2020) SW EXCLUSIVE<\/div><\/div><div class=\"play\"><\/div><div class=\"ctrl\"><div class=\"Lctrl\"><\/div><div class=\"Rctrl\"><\/div><\/div><\/div><noscript><a href=\"https:\/\/youtu.be\/dEUJwSJbKUc\" rel=\"nofollow\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/tuxproject.de\/blog\/wp-content\/plugins\/wp-youtube-lyte\/lyteCache.php?origThumbUrl=https%3A%2F%2Fi.ytimg.com%2Fvi%2FdEUJwSJbKUc%2F0.jpg\" alt=\"WHEN PLAGUES COLLIDE - TEARS OF A KING [OFFICIAL MUSIC VIDEO] (2020) SW EXCLUSIVE\" width=\"1280\" height=\"700\"><\/a><\/noscript><\/div><\/div><div class=\"lL\" style=\"max-width:100%;width:1280px;margin:5px;\"> <a href=\"https:\/\/youtu.be\/dEUJwSJbKUc\" target=\"_blank\">Die\u00adses Video auf You\u00adTube anse\u00adhen<\/a>.<\/div>\n<p>Guten Mor\u00adgen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Es ist Mon\u00adtag. RAAAAAAAH! So, geht wie\u00adder. Die Gali\u00adons\u00adfi\u00adgur der th\u00fc\u00adrin\u00adgi\u00adschen Lin\u00adken tei\u00adle mit, ent\u00adneh\u00adme ich einer ande\u00adren Publi\u00adka\u00adti\u00adon, dass Putin schlim\u00admer, weil form\u00advoll\u00adende\u00adter sei als Hit\u00adler. Da kann ja nichts mehr schief\u00adge\u00adhen bei der n\u00e4ch\u00adsten Wahl. Ein furcht\u00adba\u00adrer F\u00fch\u00adrer scheint auch bei MariaDB.com, dem Heu\u00adschrecken\u00adkon\u00adzern hin\u00adter der MariaDB-Daten\u00ad\u00ad\u00adbank, am Werk zu sein, was lustig \u2026<\/p>\n<p><a href=\"https:\/\/tuxproject.de\/blog\/2023\/04\/when-plagues-collide-tears-of-a-king-heuschrecken-und-ihre-fuehrer\/\" class=\"more-link\">\u2018When Pla\u00adgues Col\u00adl\u00adi\u00adde \u2013 Tears of a King \/\/ Heu\u00adschrecken und ihre F\u00fch\u00adrer\u2019 wei\u00adter\u00adle\u00adsen \u00bb<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"wp_typography_post_enhancements_disabled":false,"activitypub_content_warning":"","activitypub_content_visibility":"","activitypub_max_image_attachments":3,"activitypub_interaction_policy_quote":"anyone","activitypub_status":"","footnotes":""},"categories":[13,32],"tags":[],"series":[],"class_list":["post-20771","post","type-post","status-publish","format-standard","hentry","category-in-den-nachrichten","category-montagsmusik"],"share_on_mastodon":{"url":"https:\/\/social.tchncs.de\/@hirnfick_20\/110173108856733605","error":""},"wp-worthy-pixel":{"ignored":false,"public":null,"server":null,"url":null},"wp-worthy-type":"normal","_links":{"self":[{"href":"https:\/\/tuxproject.de\/blog\/wp-json\/wp\/v2\/posts\/20771","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tuxproject.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tuxproject.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tuxproject.de\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tuxproject.de\/blog\/wp-json\/wp\/v2\/comments?post=20771"}],"version-history":[{"count":0,"href":"https:\/\/tuxproject.de\/blog\/wp-json\/wp\/v2\/posts\/20771\/revisions"}],"wp:attachment":[{"href":"https:\/\/tuxproject.de\/blog\/wp-json\/wp\/v2\/media?parent=20771"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tuxproject.de\/blog\/wp-json\/wp\/v2\/categories?post=20771"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tuxproject.de\/blog\/wp-json\/wp\/v2\/tags?post=20771"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/tuxproject.de\/blog\/wp-json\/wp\/v2\/series?post=20771"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}