{"id":12901,"date":"2017-09-18T08:30:24","date_gmt":"2017-09-18T06:30:24","guid":{"rendered":"https:\/\/tuxproject.de\/blog\/?p=12901"},"modified":"2017-09-18T09:55:45","modified_gmt":"2017-09-18T07:55:45","slug":"toundra-kitsune-sechs-tage-ahnungslos","status":"publish","type":"post","link":"https:\/\/tuxproject.de\/blog\/2017\/09\/toundra-kitsune-sechs-tage-ahnungslos\/","title":{"rendered":"Toun\u00addra \u2013 Kits\u00adune \/\/ Sechs Tage ahnungs\u00adlos."},"content":{"rendered":"<p><a href=\"https:\/\/tuxproject.de\/blog\/wp-content\/uploads\/2017\/09\/Herbsteule.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/tuxproject.de\/blog\/wp-content\/uploads\/2017\/09\/Herbsteule-80x120.jpg\" title=\"Es wird Herbst, die Eulen verlieren ihre Bl\u00e4tter.\" alt=\"Es wird Herbst, die Eulen verlieren ihre Bl\u00e4tter.\" width=\"80\" height=\"120\" class=\"alignright size-thumbnail wp-image-12902\" srcset=\"https:\/\/tuxproject.de\/blog\/wp-content\/uploads\/2017\/09\/Herbsteule-80x120.jpg 80w, https:\/\/tuxproject.de\/blog\/wp-content\/uploads\/2017\/09\/Herbsteule-200x300.jpg 200w, https:\/\/tuxproject.de\/blog\/wp-content\/uploads\/2017\/09\/Herbsteule.jpg 500w\" sizes=\"auto, (max-width: 80px) 100vw, 80px\"><\/a>Es ist Mon\u00adtag; womit die Welt das ver\u00addient hat, ist jedoch lei\u00adder unklar. Beru\u00adhi\u00adgend aber ist es, dass sie ihren Humor nicht ver\u00adlo\u00adren hat: Am ver\u00adgan\u00adge\u00adnen Don\u00adners\u00adtag wur\u00adde ein Gespr\u00e4ch mit Hil\u00adla\u00adry Clin\u00adton von einem <a href=\"http:\/\/thehill.com\/media\/350815-maddow-interrupts-clinton-interview-to-show-her-sneezing-panda-video\">Video eines nie\u00adsen\u00adden Pan\u00addas<\/a> unter\u00adbro\u00adchen, anschlie\u00ad\u00dfend aber lei\u00adder fort\u00adge\u00adsetzt. Einen pr\u00e4\u00adsi\u00addia\u00adlen Pan\u00adda\u00adb\u00e4\u00adren w\u00fcr\u00adde ich jeden\u00adfalls w\u00e4h\u00adlen.<\/p>\n<p>Falls es \u00fcber\u00adhaupt so weit kommt, denn das poli\u00adti\u00adsche System ist auch hier\u00adzu\u00adlan\u00adde irri\u00adtie\u00adrend. In nur einer Woche h\u00e4t\u00adte <em>es<\/em> wie\u00adder kei\u00adner ahnen wol\u00adlen, denn Demo\u00adsko\u00adpie geht meist vom frei erfun\u00adde\u00adnen Ide\u00adal\u00adfall aus, n\u00e4m\u00adlich davon, dass Men\u00adschen strin\u00adgent han\u00addeln und Wahl\u00adpro\u00adgram\u00adme irgend\u00adet\u00adwas mit Real\u00adpo\u00adli\u00adtik zu tun haben. Dann wird wie\u00adder irgend\u00adje\u00admand betrof\u00adfen in irgend\u00adei\u00adne Kame\u00adra gucken und ver\u00adk\u00fcn\u00adden, dass <em>die Popu\u00adli\u00adsten<\/em> zwar \u201elei\u00adder\u201c irgend\u00adwo \u201edrin\u201c sei\u00aden, aber immer\u00adhin <em>iso\u00adliert<\/em>, denn tat\u00ads\u00e4ch\u00adlich hat in der bei\u00adna\u00adhe unver\u00admeid\u00adli\u00adchen knap\u00adpen Mehr\u00adheit f\u00fcr die rechts\u00adpo\u00adpu\u00adli\u00adsti\u00adsche Koali\u00adti\u00adon aus dem unhei\u00adli\u00adgen B\u00fcnd\u00adnis aus CDU und CSU sowie der Par\u00adtei des Sozi\u00adal\u00adab\u00adbaus (PdS, ehem. SPD) nie\u00admand sonst ein W\u00f6rt\u00adchen mit\u00adzu\u00adre\u00adden, was unge\u00adf\u00e4hr der Poli\u00adtik der ver\u00adgan\u00adge\u00adnen vier Jah\u00adre ent\u00adspricht: Die Iso\u00adla\u00adti\u00adon der Mehr\u00adheit als Bewah\u00adrung der Demo\u00adkra\u00adtie. Was dann kom\u00admen wird, ist abseh\u00adbar: In Medi\u00aden, die nicht ver\u00adlinkt wer\u00adden m\u00f6ch\u00adten, for\u00adder\u00adte die\u00adser Tage der heu\u00adte sei\u00adnen 75. Geburts\u00adtag fei\u00adern\u00adden (weil \u201ebege\u00adhen\u00adden\u201c doch recht unchar\u00admant w\u00e4re) Wolf\u00adgang Sch\u00e4ub\u00adle eine Ren\u00adte ab 70 Jah\u00adren. Ich bin ja sel\u00adten sei\u00adner Mei\u00adnung, fin\u00adde aber, er hat Ren\u00adte wirk\u00adlich drin\u00adgend n\u00f6tig.<\/p>\n<p>Neu\u00ades aus der Geschlech\u00adter\u00adfor\u00adschung: <a href=\"https:\/\/digest.bps.org.uk\/2017\/09\/14\/autistic-boys-and-girls-found-to-have-hypermasculinised-faces-supporting-the-extreme-male-brain-theory\/\">Auti\u00adsten bei\u00adder\u00adlei Geschlechts haben beson\u00adders m\u00e4nn\u00adli\u00adche Gesich\u00adter<\/a>, von einer Auti\u00adsten\u00adquo\u00adte in F\u00fch\u00adrungs\u00adpo\u00adsi\u00adtio\u00adnen ist daher ver\u00admut\u00adlich gleich dop\u00adpelt Abstand zu neh\u00admen. Ande\u00adrer\u00adseits: Um irgend\u00adwo als Chief Secu\u00adri\u00adty Offi\u00adcer anfan\u00adgen zu d\u00fcr\u00adfen, reicht ja auch ein <a href=\"https:\/\/blog.fefe.de\/?ts=a742b631\">Musik\u00adstu\u00addi\u00adum<\/a> aus.<\/p>\n<p>Passt ja, f\u00fcr Logik sind sich sowie\u00adso die mei\u00adsten Bran\u00adchen zu fein: Der Nutz\u00adlos\u00addienst Golem.de <a href=\"https:\/\/www.golem.de\/news\/smarte-lautsprecher-south-park-folge-nimmt-alexa-und-google-assistant-ins-visier-1709-130100.html\">behaup\u00adte\u00adte<\/a> gestern, bei \u201eAle\u00adxa\u201c und \u201eGoog\u00adle Assi\u00adstant\u201c han\u00adde\u00adle es sich um \u201esmar\u00adte Laut\u00adspre\u00adcher\u201c, w\u00e4h\u00adrend <em>zu mei\u00adner Zeit<\/em> Ger\u00e4\u00adte, in die man rein\u00adspricht und die dann irgend\u00adwas machen, noch \u201eMikro\u00adfo\u00adne\u201c (wenn sicht\u00adbar) oder \u201eWan\u00adzen\u201c (wenn nicht so offen\u00adsicht\u00adlich sicht\u00adbar) hie\u00ad\u00dfen. Ger\u00e4\u00adte, die <em>smar\u00adter<\/em> sind als die\u00adje\u00adni\u00adgen, die \u00fcber sie berich\u00adten: Das ist wohl die\u00adse <em>Zukunft<\/em>, von der immer alle reden.<\/p>\n<p>Da hal\u00adte ich mich doch lie\u00adber an die Ver\u00adgan\u00adgen\u00adheit, zum Bei\u00adspiel an das Jahr 2016.<\/p>\n<div class=\"lyte-wrapper\" title=\"Toundra - KITSUNE\" style=\"width:1280px;max-width:100%;margin:5px;\"><div class=\"lyMe\" id=\"WYL_NwXZ3kZGq3A\"><div id=\"lyte_NwXZ3kZGq3A\" data-src=\"https:\/\/tuxproject.de\/blog\/wp-content\/plugins\/wp-youtube-lyte\/lyteCache.php?origThumbUrl=https%3A%2F%2Fi.ytimg.com%2Fvi%2FNwXZ3kZGq3A%2Fhqdefault.jpg\" class=\"pL\"><div class=\"tC\"><div class=\"tT\">Toun\u00addra \u2013 KITSUNE<\/div><\/div><div class=\"play\"><\/div><div class=\"ctrl\"><div class=\"Lctrl\"><\/div><div class=\"Rctrl\"><\/div><\/div><\/div><noscript><a href=\"https:\/\/youtu.be\/NwXZ3kZGq3A\" rel=\"nofollow\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/tuxproject.de\/blog\/wp-content\/plugins\/wp-youtube-lyte\/lyteCache.php?origThumbUrl=https%3A%2F%2Fi.ytimg.com%2Fvi%2FNwXZ3kZGq3A%2F0.jpg\" alt=\"Toundra - KITSUNE\" width=\"1280\" height=\"700\"><\/a><\/noscript><\/div><\/div><div class=\"lL\" style=\"max-width:100%;width:1280px;margin:5px;\"> <a href=\"https:\/\/youtu.be\/NwXZ3kZGq3A\" target=\"_blank\">Die\u00adses Video auf You\u00adTube anse\u00adhen<\/a>.<\/div>\n<p>Guten Mor\u00adgen.<\/p>\n<hr>\n<p>In eige\u00adner Sache: Ich habe mein Word\u00adPress-Plug\u00adin <a href=\"https:\/\/tuxproject.de\/blog\/2013\/08\/wahl-schwach-o-mat\/\">WP-Wahl\u00adB\u00adlack\u00adout<\/a> f\u00fcr die anste\u00adhen\u00adde Bun\u00addes\u00adtags\u00adwahl ein biss\u00adchen \u00fcber\u00adar\u00adbei\u00adtet, unter ande\u00adrem mit etwas sinn\u00advol\u00adle\u00adren Ver\u00adwei\u00adsen auf der mit\u00adge\u00adlie\u00adfer\u00adten, aber immer noch zweck\u00adm\u00e4\u00ad\u00dfig gestal\u00adte\u00adten Abschalt\u00adsei\u00adte. Wer es nut\u00adzen m\u00f6ch\u00adte, der m\u00f6ge das tun.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Es ist Mon\u00adtag; womit die Welt das ver\u00addient hat, ist jedoch lei\u00adder unklar. Beru\u00adhi\u00adgend aber ist es, dass sie ihren Humor nicht ver\u00adlo\u00adren hat: Am ver\u00adgan\u00adge\u00adnen Don\u00adners\u00adtag wur\u00adde ein Gespr\u00e4ch mit Hil\u00adla\u00adry Clin\u00adton von einem Video eines nie\u00adsen\u00adden Pan\u00addas unter\u00adbro\u00adchen, anschlie\u00ad\u00dfend aber lei\u00adder fort\u00adge\u00adsetzt. Einen pr\u00e4\u00adsi\u00addia\u00adlen Pan\u00adda\u00adb\u00e4\u00adren w\u00fcr\u00adde ich jeden\u00adfalls w\u00e4h\u00adlen. Falls es \u00fcber\u00adhaupt so \u2026<\/p>\n<p><a href=\"https:\/\/tuxproject.de\/blog\/2017\/09\/toundra-kitsune-sechs-tage-ahnungslos\/\" class=\"more-link\">\u2018Toun\u00addra \u2013 Kits\u00adune \/\/ Sechs Tage ahnungs\u00adlos.\u2019 wei\u00adter\u00adle\u00adsen \u00bb<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"wp_typography_post_enhancements_disabled":false,"activitypub_content_warning":"","activitypub_content_visibility":"","activitypub_max_image_attachments":3,"activitypub_interaction_policy_quote":"anyone","activitypub_status":"","footnotes":""},"categories":[4,32],"tags":[],"series":[],"class_list":["post-12901","post","type-post","status-publish","format-standard","hentry","category-politik","category-montagsmusik"],"share_on_mastodon":{"url":"","error":""},"wp-worthy-pixel":{"ignored":false,"public":null,"server":null,"url":null},"wp-worthy-type":"normal","_links":{"self":[{"href":"https:\/\/tuxproject.de\/blog\/wp-json\/wp\/v2\/posts\/12901","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tuxproject.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tuxproject.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tuxproject.de\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tuxproject.de\/blog\/wp-json\/wp\/v2\/comments?post=12901"}],"version-history":[{"count":0,"href":"https:\/\/tuxproject.de\/blog\/wp-json\/wp\/v2\/posts\/12901\/revisions"}],"wp:attachment":[{"href":"https:\/\/tuxproject.de\/blog\/wp-json\/wp\/v2\/media?parent=12901"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tuxproject.de\/blog\/wp-json\/wp\/v2\/categories?post=12901"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tuxproject.de\/blog\/wp-json\/wp\/v2\/tags?post=12901"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/tuxproject.de\/blog\/wp-json\/wp\/v2\/series?post=12901"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}