{"id":12782,"date":"2017-08-24T21:06:06","date_gmt":"2017-08-24T19:06:06","guid":{"rendered":"https:\/\/tuxproject.de\/blog\/?p=12782"},"modified":"2017-08-24T21:06:06","modified_gmt":"2017-08-24T19:06:06","slug":"warum-basisdemokratie-kein-blankoscheck-sein-darf","status":"publish","type":"post","link":"https:\/\/tuxproject.de\/blog\/2017\/08\/warum-basisdemokratie-kein-blankoscheck-sein-darf\/","title":{"rendered":"War\u00adum Basis\u00adde\u00admo\u00adkra\u00adtie kein Blan\u00adko\u00adscheck sein darf"},"content":{"rendered":"<p>Davon, dass die zeit\u00adli\u00adche N\u00e4he zwi\u00adschen dem Nie\u00adder\u00adgang der Hacker\u00adkul\u00adtur und dem gesell\u00adschaft\u00adli\u00adchen Auf\u00adstieg von Leu\u00adten, deren wesent\u00adli\u00adches Inter\u00ades\u00adse der Neu\u00adde\u00adfi\u00adni\u00adti\u00adon ihres Geschlechts gilt, war hier <a href=\"https:\/\/tuxproject.de\/blog\/2016\/01\/der-zusammenbruch-der-hackerkultur-durch-den-siegeszug-des-twitterfeminismus\/\">bereits 2016<\/a> die Rede, ich stell\u00adte hier\u00adf\u00fcr einen Zusam\u00admen\u00adhang zwi\u00adschen dem Cha\u00ados Com\u00adpu\u00adter Club und der Pira\u00adten\u00adpar\u00adtei her, wobei ich ins\u00adbe\u00adson\u00adde\u00adre die Fol\u00adgen f\u00fcr erste\u00adren Ver\u00adein the\u00adma\u00adti\u00adsier\u00adte. Aus aktu\u00adel\u00adlem Anlass m\u00f6ch\u00adte ich heu\u00adte ein\u00admal die ande\u00adre Sei\u00adte gering\u00adf\u00fc\u00adgig genau\u00ader beleuch\u00adten.<\/p>\n<p>Es gibt n\u00e4m\u00adlich gute Gr\u00fcn\u00adde, dass es meh\u00adre\u00adre Par\u00adtei\u00aden gibt, und die\u00adse lie\u00adgen nicht nur dar\u00adin, dass die Exi\u00adstenz nur einer Par\u00adtei dem jeden\u00adfalls papier\u00adnen Anspruch der Repr\u00e4\u00adsen\u00adta\u00adti\u00adon des gan\u00adzen hete\u00adro\u00adge\u00adnen Volks zuwi\u00adder\u00adlie\u00adfe, wes\u00adwe\u00adgen im \u00dcbri\u00adgen auch eine pro\u00adzen\u00adtua\u00adle \u201eH\u00fcr\u00adde\u201c f\u00fcr den Ein\u00adstieg in irgend\u00adein Par\u00adla\u00adment mei\u00adner Auf\u00adfas\u00adsung von Volks\u00adver\u00adtre\u00adtung nicht ent\u00adspricht. Es gibt, bewusst grif\u00adfig ver\u00adk\u00fcrzt, mit den \u201eGr\u00fc\u00adnen\u201c eine \u00d6ko\u00adpar\u00adtei, es gibt mit der SPD eine ehe\u00adma\u00adli\u00adge Arbei\u00adter\u00adpar\u00adtei, es gibt eine BGE-Par\u00adtei die\u00adses Namens, es gibt eine erschreckend apo\u00adli\u00adti\u00adsche \u201ePar\u00adtei\u201c namens PARTEI, es gibt mit der \u201eUni\u00adon\u201c sogar zwei Par\u00adtei\u00aden f\u00fcr den poli\u00adtisch apa\u00adthi\u00adschen Durch\u00adschnitts\u00adb\u00fcr\u00adger; es gibt au\u00dfer\u00addem eine Par\u00adtei, die sich f\u00fcr netz\u00adpo\u00adli\u00adti\u00adsche Belan\u00adge ein\u00adzu\u00adset\u00adzen pfleg\u00adte, und ihr Name ist Pira\u00adten\u00adpar\u00adtei.<\/p>\n<p>Die Pira\u00adten\u00adpar\u00adtei, auf\u00adge\u00adbaut in und dank der Annah\u00adme, jeder Bei\u00adtrag sei eine gro\u00ad\u00dfe Hil\u00adfe bei der Umset\u00adzung der poli\u00adti\u00adschen Pl\u00e4\u00adne, was sp\u00e4\u00adter als \u201eBasis\u00adde\u00admo\u00adkra\u00adtie\u201c zusam\u00admen\u00adge\u00adfasst wur\u00adde, k\u00e4mpf\u00adte \u00fcber\u00adzeu\u00adgend daf\u00fcr, dass die Belan\u00adge derer, die 2017 kol\u00adlek\u00adtiv belei\u00addi\u00adgend als \u201edie Netz\u00adge\u00admein\u00adde\u201c bezeich\u00adnet wer\u00adden, als sei <em>das Netz<\/em> eine abweich\u00adler\u00adfreie Sek\u00adte und kein Kom\u00admu\u00adni\u00adka\u00adti\u00adons\u00adme\u00addi\u00adum, eine gr\u00f6\u00ad\u00dfe\u00adre Rol\u00adle in der Bun\u00addes\u00adpo\u00adli\u00adtik spie\u00adlen soll\u00adten. Bedau\u00ader\u00adli\u00adcher\u00adwei\u00adse wur\u00adde die Bereit\u00adschaft, kei\u00adnen am The\u00adma Inter\u00ades\u00adsier\u00adten abzu\u00adwei\u00adsen, bald der\u00adge\u00adstalt fehl\u00adin\u00adter\u00adpre\u00adtiert, dass davon aus\u00adge\u00adgan\u00adgen wur\u00adde, dass jede noch so bescheu\u00ader\u00adte Idee, der in ande\u00adren Par\u00adtei\u00aden nicht genug zuge\u00adh\u00f6rt wur\u00adde, bei der Pira\u00adten\u00adpar\u00adtei gut auf\u00adge\u00adho\u00adben sei, von Kern\u00adkraft\u00adkri\u00adtik \u00fcber Radi\u00adkal\u00adfe\u00admi\u00adnis\u00admus bis hin zum lei\u00adstungs\u00adlo\u00adsen Gra\u00adtis\u00adgeld (\u201eBGE\u201c).<\/p>\n<p>Dass das kla\u00adre und von <em>allen ande\u00adren deut\u00adschen Par\u00adtei\u00aden<\/em> weit ent\u00adfern\u00adte, somit ein\u00adma\u00adli\u00adge Pro\u00adfil der Par\u00adtei, die sich f\u00fcr eine poli\u00adti\u00adsche Inte\u00adgra\u00adti\u00adon des Inter\u00adnets in gesell\u00adschaft\u00adli\u00adche Fra\u00adgen ein\u00adsetzt, seit 2011 zuse\u00adhends mehr ver\u00adw\u00e4s\u00adsert wur\u00adde, ist Teil des Pro\u00adblems, des\u00adsen Fol\u00adgen sich in per\u00adver\u00adser Gesetz\u00adge\u00adbung und Ver\u00admeh\u00adrung von \u00dcber\u00adwa\u00adchungs\u00adme\u00adcha\u00adnis\u00admen zei\u00adgen, und es gibt <em>gute Gr\u00fcn\u00adde<\/em>, dar\u00adan den\u00adje\u00adni\u00adgen eine per\u00ads\u00f6n\u00adli\u00adche Schuld zu geben, die den Unter\u00adschied zwi\u00adschen der Hil\u00adfe beim Auf\u00adbau einer schlag\u00adkr\u00e4f\u00adti\u00adgen Par\u00adtei\u00adba\u00adsis und der M\u00f6g\u00adlich\u00adkeit, sei\u00adne eige\u00adne Agen\u00adda zu publi\u00adzie\u00adren, nicht ver\u00adstan\u00adden haben.<\/p>\n<p>Ich erkl\u00e4\u00adre das Pro\u00adblem ein\u00admal mit einer Ana\u00adlo\u00adgie: Neh\u00admen wir an, es gibt jeman\u00adden, der zu Hau\u00adse \u201ekein Inter\u00adnet\u201c hat und des\u00adsen Hob\u00adbys R\u00fcben\u00adzucht und Tau\u00adben\u00adjagd sind. Wel\u00adche Par\u00adtei ver\u00adtritt sei\u00adne per\u00ads\u00f6n\u00adli\u00adchen Inter\u00ades\u00adsen am besten, in wel\u00adcher w\u00fcr\u00adde er sich will\u00adkom\u00admen f\u00fch\u00adlen und gar mit sei\u00adner Exper\u00adti\u00adse die\u00adse Par\u00adtei vor\u00adan\u00adbrin\u00adgen? In einer netz\u00adpo\u00adli\u00adti\u00adschen, einer wirt\u00adschafts\u00adori\u00aden\u00adtier\u00adten gar?<\/p>\n<p>Eine Par\u00adtei, man ver\u00adzei\u00adhe mir den Zir\u00adkel\u00adschluss, hei\u00dft Par\u00adtei, weil sie Par\u00adtei f\u00fcr eine bestimm\u00adte Grup\u00adpe (ihre Kli\u00aden\u00adtel, ihre <em>Stamm\u00adw\u00e4h\u00adler\u00adschaft<\/em> eben) ergreift, nicht aber zwangs\u00adl\u00e4u\u00adfig f\u00fcr jeden gei\u00adsti\u00adgen Total\u00adaus\u00adfall, der gera\u00adde was sagen will. Offe\u00adne Arme f\u00fcr jeden Fan\u00adta\u00adsten haben schon ganz ande\u00adre Pro\u00adjek\u00adte als blo\u00df eine Par\u00adtei zer\u00adst\u00f6rt. Wenn jemand offen\u00adsicht\u00adlich v\u00f6l\u00adlig ande\u00adre poli\u00adti\u00adsche Vor\u00adstel\u00adlun\u00adgen als ich selbst habe, dann neh\u00adme ich das zur Kennt\u00adnis, wei\u00df aber auch, dass ein Kon\u00adsens nicht funk\u00adtio\u00adnie\u00adren kann, wes\u00adhalb ich die\u00adsen Jemand auch nicht \u201eein\u00adzu\u00adbin\u00adden\u201c und \u201eteil\u00adha\u00adben\u201c zu las\u00adsen ver\u00adsu\u00adche. Es ist ein gewal\u00adti\u00adger Feh\u00adler, als Par\u00adtei anzu\u00adneh\u00admen, dass jeder Knall\u00adkopf Geh\u00f6r fin\u00adden soll\u00adte, wof\u00fcr Zeit geop\u00adfert wer\u00adden m\u00fcss\u00adte, die statt\u00addes\u00adsen auch in sinn\u00advol\u00adle\u00adre T\u00e4tig\u00adkei\u00adten, zum Bei\u00adspiel f\u00fcr den Kampf f\u00fcr anst\u00e4n\u00addi\u00adge Netz\u00adpo\u00adli\u00adtik, inve\u00adstiert wer\u00adden k\u00f6nn\u00adte. Par\u00adtei\u00aden sind kei\u00adne Buch\u00adklubs.<\/p>\n<p>Die Pira\u00adten\u00adpar\u00adtei \u2013 Offen\u00adle\u00adgung: noch immer mit mei\u00adner Mit\u00adglied\u00adschaft aus\u00adge\u00adstat\u00adtet \u2013 ist kon\u00adzep\u00adtio\u00adnell eine netz\u00adpo\u00adli\u00adti\u00adsche Par\u00adtei, zusam\u00admen\u00adge\u00adsetzt zwei\u00adfel\u00adlos aus Men\u00adschen ver\u00adschie\u00adden\u00adster Art. Dage\u00adgen ist prin\u00adzi\u00adpi\u00adell nichts ein\u00adzu\u00adwen\u00adden. Wer jedoch zwar vor viel\u00adf\u00e4l\u00adti\u00adgen Ideen nur so \u00fcber\u00adsch\u00e4umt, jedoch kei\u00adner\u00adlei Inter\u00ades\u00adse an einer moder\u00adnen Netz- oder wenig\u00adstens Urhe\u00adber\u00adrechts\u00adpo\u00adli\u00adtik hat, der ist in einer poli\u00adti\u00adschen, inner\u00adpar\u00adtei\u00adli\u00adchen Dis\u00adkus\u00adsi\u00adon mit <em>mir per\u00ads\u00f6n\u00adlich<\/em> nicht will\u00adkom\u00admen, weil er anders als die\u00adje\u00adni\u00adgen, die wenig\u00adstens in den The\u00admen, die der Pira\u00adten\u00adpar\u00adtei \u00fcber\u00adhaupt einen Grund zum Fort\u00adbe\u00adstand ver\u00adlei\u00adhen, eine dis\u00adkus\u00adsi\u00adons\u00adw\u00fcr\u00addi\u00adge Mei\u00adnung ver\u00adtre\u00adten, ledig\u00adlich ein Klotz am Bein w\u00e4re, denn er hat zur Umset\u00adzung der Zie\u00adle, f\u00fcr die die\u00adse Par\u00adtei <em>\u00fcber\u00adhaupt exi\u00adstiert<\/em>, nichts bei\u00adzu\u00adtra\u00adgen, was es wert w\u00e4re, geh\u00f6rt zu wer\u00adden.<\/p>\n<p>Eine Par\u00adtei muss auch mal sagen: Leu\u00adte, ihr seid uns hier echt im Weg.<\/p>\n<p><em>(Zweit\u00adver\u00adwer\u00adtet aus einer Dis\u00adkus\u00adsi\u00adon auf Twit\u00adter.)<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Davon, dass die zeit\u00adli\u00adche N\u00e4he zwi\u00adschen dem Nie\u00adder\u00adgang der Hacker\u00adkul\u00adtur und dem gesell\u00adschaft\u00adli\u00adchen Auf\u00adstieg von Leu\u00adten, deren wesent\u00adli\u00adches Inter\u00ades\u00adse der Neu\u00adde\u00adfi\u00adni\u00adti\u00adon ihres Geschlechts gilt, war hier bereits 2016 die Rede, ich stell\u00adte hier\u00adf\u00fcr einen Zusam\u00admen\u00adhang zwi\u00adschen dem Cha\u00ados Com\u00adpu\u00adter Club und der Pira\u00adten\u00adpar\u00adtei her, wobei ich ins\u00adbe\u00adson\u00adde\u00adre die Fol\u00adgen f\u00fcr erste\u00adren Ver\u00adein the\u00adma\u00adti\u00adsier\u00adte. Aus aktu\u00adel\u00adlem \u2026<\/p>\n<p><a href=\"https:\/\/tuxproject.de\/blog\/2017\/08\/warum-basisdemokratie-kein-blankoscheck-sein-darf\/\" class=\"more-link\">\u2018War\u00adum Basis\u00adde\u00admo\u00adkra\u00adtie kein Blan\u00adko\u00adscheck sein darf\u2019 wei\u00adter\u00adle\u00adsen \u00bb<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"wp_typography_post_enhancements_disabled":false,"activitypub_content_warning":"","activitypub_content_visibility":"","activitypub_max_image_attachments":3,"activitypub_interaction_policy_quote":"anyone","activitypub_status":"","footnotes":""},"categories":[1,20],"tags":[],"series":[],"class_list":["post-12782","post","type-post","status-publish","format-standard","hentry","category-persoenliches","category-piratenpartei"],"share_on_mastodon":{"url":"","error":""},"wp-worthy-pixel":{"ignored":false,"public":null,"server":null,"url":null},"wp-worthy-type":"normal","_links":{"self":[{"href":"https:\/\/tuxproject.de\/blog\/wp-json\/wp\/v2\/posts\/12782","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tuxproject.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tuxproject.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tuxproject.de\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tuxproject.de\/blog\/wp-json\/wp\/v2\/comments?post=12782"}],"version-history":[{"count":0,"href":"https:\/\/tuxproject.de\/blog\/wp-json\/wp\/v2\/posts\/12782\/revisions"}],"wp:attachment":[{"href":"https:\/\/tuxproject.de\/blog\/wp-json\/wp\/v2\/media?parent=12782"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tuxproject.de\/blog\/wp-json\/wp\/v2\/categories?post=12782"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tuxproject.de\/blog\/wp-json\/wp\/v2\/tags?post=12782"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/tuxproject.de\/blog\/wp-json\/wp\/v2\/series?post=12782"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}